{"id":1366,"date":"2025-03-01T15:36:13","date_gmt":"2025-03-01T18:36:13","guid":{"rendered":"https:\/\/mascoweb.com.ar\/tienda\/?post_type=product&#038;p=1366"},"modified":"2026-06-24T16:09:49","modified_gmt":"2026-06-24T19:09:49","slug":"excellent-puppy-mediano-grande-x20kg","status":"publish","type":"product","link":"https:\/\/mascoweb.com.ar\/tienda\/producto\/excellent-puppy-mediano-grande-x20kg\/","title":{"rendered":"Excellent Pollo y Arroz Puppy Razas Medianas y Grandes x 20 kg"},"content":{"rendered":"<h5>Excellent Puppy Razas Medianas y Grandes x 20 kg<\/h5>\n<p>Con el sistema SMART NUTRITION BY PURINA\u00ae, que aporta m\u00faltiples beneficios cient\u00edficamente comprobados, que mantienen a tu cachorro con un excelente estado de salud.<\/p>\n<p><strong>Contribuye a un crecimiento \u00f3ptimo y al desarrollo saludable del sistema inmune<\/strong><br \/>\nCon antioxidantes como la vitamina E y selenio, adem\u00e1s de prote\u00edna de alta digestibilidad que contribuyen a fortalecer las defensas y a mantener un sistema inmune saludable.<\/p>\n<p><strong>Con DHA que ayuda al desarrollo adecuado del cerebro y la visi\u00f3n<\/strong><br \/>\nCon DHA proveniente de fuentes de pescado y\/o de alga, cumple una funci\u00f3n clave para el desarrollo saludable del cerebro del cachorro. En combinaci\u00f3n con la Vitamina A que favorece al desarrollo adecuado de la visi\u00f3n.<\/p>\n<p><strong>Favorece dientes y huesos fuertes<\/strong><br \/>\nEl aporte de minerales clave como calcio y f\u00f3sforo en proporciones adecuadas ayuda al desarrollo saludable de dientes y huesos.<\/p>\n<p><strong>Promueve una \u00f3ptima absorci\u00f3n de nutrientes y la formaci\u00f3n de heces firmes<\/strong><br \/>\nLa inclusi\u00f3n del prebi\u00f3tico natural ayuda a optimizar el equilibrio intestinal, colaborando con una buena salud digestiva y una \u00f3ptima absorci\u00f3n de nutrientes.<br \/>\nCon zeolita (fuente mineral) y fibra natural que ayudan a producir heces firmes.<\/p>\n","protected":false},"excerpt":{"rendered":"<h5>Excellent Puppy Razas Medianas y Grandes x 20 kg<\/h5>\n<p>PURINA\u00ae EXCELLENT\u2122 le ofrece a tu cachorro una nutrici\u00f3n que favorece su desarrollo y crecimiento. Con prote\u00ednas de alta calidad y antioxidantes como la vitamina E y selenio, que contribuyen a fortalecer las defensas y a mantener un sistema inmune saludable.<\/p>\n","protected":false},"featured_media":1886,"template":"","meta":{"_gspb_post_css":"","_joinchat":[]},"product_brand":[58],"product_cat":[29,23,138],"product_tag":[41,33,63],"class_list":["post-1366","product","type-product","status-publish","has-post-thumbnail","product_brand-excellent","product_cat-alimentoparaperros","product_cat-alimentosbalanceados","product_cat-perroscachorros","product_tag-20kg","product_tag-cachorros","product_tag-superpremium","first","instock","shipping-taxable","purchasable","product-type-simple"],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/mascoweb.com.ar\/tienda\/wp-json\/wp\/v2\/product\/1366","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mascoweb.com.ar\/tienda\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/mascoweb.com.ar\/tienda\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mascoweb.com.ar\/tienda\/wp-json\/wp\/v2\/media\/1886"}],"wp:attachment":[{"href":"https:\/\/mascoweb.com.ar\/tienda\/wp-json\/wp\/v2\/media?parent=1366"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/mascoweb.com.ar\/tienda\/wp-json\/wp\/v2\/product_brand?post=1366"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/mascoweb.com.ar\/tienda\/wp-json\/wp\/v2\/product_cat?post=1366"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/mascoweb.com.ar\/tienda\/wp-json\/wp\/v2\/product_tag?post=1366"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}