{"id":2182,"date":"2025-03-18T18:03:30","date_gmt":"2025-03-18T21:03:30","guid":{"rendered":"https:\/\/mascoweb.com.ar\/tienda\/?post_type=product&#038;p=2182"},"modified":"2026-05-04T12:29:18","modified_gmt":"2026-05-04T15:29:18","slug":"gran-campeon-adultos-mantenimiento-x-213-kg","status":"publish","type":"product","link":"https:\/\/mascoweb.com.ar\/tienda\/producto\/gran-campeon-adultos-mantenimiento-x-213-kg\/","title":{"rendered":"Gran Campe\u00f3n Adultos Mantenimiento x 21+3 kg"},"content":{"rendered":"<h5>Gran Campe\u00f3n Adultos Mantenimiento x 21 kg + 3 kg de regalo!<\/h5>\n<p>Alimento completo para perros adultos<\/p>\n<p><strong>21% de prote\u00ednas<\/strong><\/p>\n<p>Entre sus ingredientes:<br \/>\nL-Glutamina: colabora con la salud intestinal.<br \/>\nManano-Oligosac\u00e1ridos (MOS): favorecen la flora intestinal.<br \/>\nL-Carnitina: colabora con la musculaci\u00f3n magra.<br \/>\nOmega 3 y 6: refuerzan la barrera cut\u00e1nea.<br \/>\nCynara Colymus: contribuye a los procesos digestivos.<\/p>\n","protected":false},"excerpt":{"rendered":"<h5>Gran Campe\u00f3n Adultos Mantenimiento x 21 kg + 3 kg de regalo!<\/h5>\n<p>Alimento completo para perros adultos<\/p>\n<p><strong>21% de prote\u00ednas<\/strong><\/p>\n<p>Entre sus ingredientes:<br \/>\nL-Glutamina: colabora con la salud intestinal.<br \/>\nManano-Oligosac\u00e1ridos (MOS): favorecen la flora intestinal.<br \/>\nL-Carnitina: colabora con la musculaci\u00f3n magra.<br \/>\nOmega 3 y 6: refuerzan la barrera cut\u00e1nea.<br \/>\nCynara Colymus: contribuye a los procesos digestivos.<\/p>\n","protected":false},"featured_media":2745,"template":"","meta":{"_gspb_post_css":"","_joinchat":[]},"product_brand":[69],"product_cat":[137,29,62,61],"product_tag":[38,32,65],"class_list":{"0":"post-2182","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_brand-gran-campeon","7":"product_cat-perrosadultos","8":"product_cat-alimentoparaperros","9":"product_cat-kilos-de-regalo","10":"product_cat-promociones","11":"product_tag-24kg","12":"product_tag-adultos","13":"product_tag-lineamedia","15":"first","16":"instock","17":"shipping-taxable","18":"purchasable","19":"product-type-simple"},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/mascoweb.com.ar\/tienda\/wp-json\/wp\/v2\/product\/2182","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mascoweb.com.ar\/tienda\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/mascoweb.com.ar\/tienda\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mascoweb.com.ar\/tienda\/wp-json\/wp\/v2\/media\/2745"}],"wp:attachment":[{"href":"https:\/\/mascoweb.com.ar\/tienda\/wp-json\/wp\/v2\/media?parent=2182"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/mascoweb.com.ar\/tienda\/wp-json\/wp\/v2\/product_brand?post=2182"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/mascoweb.com.ar\/tienda\/wp-json\/wp\/v2\/product_cat?post=2182"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/mascoweb.com.ar\/tienda\/wp-json\/wp\/v2\/product_tag?post=2182"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}