{"id":2654,"date":"2025-05-21T16:44:43","date_gmt":"2025-05-21T19:44:43","guid":{"rendered":"https:\/\/mascoweb.com.ar\/tienda\/?post_type=product&#038;p=2654"},"modified":"2026-04-27T09:56:35","modified_gmt":"2026-04-27T12:56:35","slug":"dogui-adultos-x-213-kg","status":"publish","type":"product","link":"https:\/\/mascoweb.com.ar\/tienda\/producto\/dogui-adultos-x-213-kg\/","title":{"rendered":"Dogui Adultos x 21+3 kg"},"content":{"rendered":"<h5>Dogui Adultos con Carne, Pollo, Cereales y Vegetales x 21+3 kg<\/h5>\n<p>Alimento completo y balanceado para perros adultos de todos los tama\u00f1os.<\/p>\n<p><strong>Beneficios<\/strong><\/p>\n<p>Cuidadosamente formulado con todo lo que tu perro necesita, y nada de lo que no:<\/p>\n<ul>\n<li>4 Fuentes de prote\u00edna: carne, pollo,\u00a0<a>soja<\/a>\u00a0y\u00a0ma\u00edz.<\/li>\n<li>40% \/ 60% de prote\u00edna\u00a0animal\/vegetal.<\/li>\n<li>Sin colorantes artificiales\u00a0a\u00f1adidos.<\/li>\n<li>M\u00e1s sabor en el alimento de su perro**.<\/li>\n<\/ul>\n<p><strong>Ingredientes:<\/strong><\/p>\n<p>Ma\u00edz; harina de soja; subproductos de ma\u00edz y\/o soja y\/o trigo; harina de carne y hueso vacuna y\/o porcina; harina de subproductos de pollo; grasa vacuna y\/o aceite de pollo preservados con tocoferoles mezclados (fuente de vitamina E); cloruro de sodio y\/o cloruro de potasio; carbonato de calcio y\/o fosfato c\u00e1lcico; trigo y\/o sorgo; hidrolizado (en polvo y\/o l\u00edquido) a base de subproductos de pollo y\/o cerdo y\/o hemoglobina vacuna y\/o porcina en polvo; arroz; suplemento vitam\u00ednico antioxidante (A, D3, E, K3, B1, B2, B3, B5, B6, B7, B9, B12, BHT); suplementos minerales [sulfatos (zinc, hierro, manganeso, cobre), yodato de calcio, selenito de sodio]; cloruro de colina; DL-metionina; arveja deshidratada; espinaca deshidratada; zanahoria deshidratada.<\/p>\n<table class=\"table striped internal-products-section-accordion-body-table\">\n<thead>\n<tr>\n<th scope=\"col\">Nutriente<\/th>\n<th scope=\"col\">M\u00edn.<\/th>\n<th scope=\"col\">M\u00e1x.<\/th>\n<\/tr>\n<\/thead>\n<tbody>\n<tr>\n<td class=\"p-2\">Humedad<\/td>\n<td class=\"p-2\">&#8211;<\/td>\n<td class=\"p-2\">12,0%<\/td>\n<\/tr>\n<tr>\n<td class=\"p-2\">Prote\u00edna cruda<\/td>\n<td class=\"p-2\">19,0%<\/td>\n<td class=\"p-2\">&#8211;<\/td>\n<\/tr>\n<tr>\n<td class=\"p-2\">Extracto Et\u00e9reo\/Grasa Bruta<\/td>\n<td class=\"p-2\">7,0%<\/td>\n<td class=\"p-2\">&#8211;<\/td>\n<\/tr>\n<tr>\n<td class=\"p-2\">Fibra Bruta<\/td>\n<td class=\"p-2\">&#8211;<\/td>\n<td class=\"p-2\">5,5%<\/td>\n<\/tr>\n<tr>\n<td class=\"p-2\">Minerales\/Cenizas<\/td>\n<td class=\"p-2\">&#8211;<\/td>\n<td class=\"p-2\">9,5%<\/td>\n<\/tr>\n<tr>\n<td class=\"p-2\">Calcio<\/td>\n<td class=\"p-2\">1,0%<\/td>\n<td class=\"p-2\">2,0%<\/td>\n<\/tr>\n<tr>\n<td class=\"p-2\">F\u00f3sforo<\/td>\n<td class=\"p-2\">0,60%<\/td>\n<td class=\"p-2\">1,4%<\/td>\n<\/tr>\n<tr>\n<td class=\"p-2\">Energ\u00eda Metabolizable (calculada): 3.400 kcal\/kg<\/td>\n<td class=\"p-2\"><\/td>\n<td class=\"p-2\"><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n","protected":false},"excerpt":{"rendered":"<h5>Dogui Adultos con Carne, Pollo, Cereales y Vegetales x 21+3 kg<\/h5>\n<p>Alimento completo y balanceado para perros adultos de todos los tama\u00f1os.<\/p>\n","protected":false},"featured_media":2365,"template":"","meta":{"_gspb_post_css":"","_joinchat":[]},"product_brand":[123],"product_cat":[137,62],"product_tag":[38,32,66],"class_list":["post-2654","product","type-product","status-publish","has-post-thumbnail","product_brand-dogui","product_cat-perrosadultos","product_cat-kilos-de-regalo","product_tag-24kg","product_tag-adultos","product_tag-lineamediaeconomica","first","instock","shipping-taxable","purchasable","product-type-simple"],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/mascoweb.com.ar\/tienda\/wp-json\/wp\/v2\/product\/2654","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mascoweb.com.ar\/tienda\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/mascoweb.com.ar\/tienda\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mascoweb.com.ar\/tienda\/wp-json\/wp\/v2\/media\/2365"}],"wp:attachment":[{"href":"https:\/\/mascoweb.com.ar\/tienda\/wp-json\/wp\/v2\/media?parent=2654"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/mascoweb.com.ar\/tienda\/wp-json\/wp\/v2\/product_brand?post=2654"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/mascoweb.com.ar\/tienda\/wp-json\/wp\/v2\/product_cat?post=2654"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/mascoweb.com.ar\/tienda\/wp-json\/wp\/v2\/product_tag?post=2654"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}