{"id":2954,"date":"2025-10-24T09:35:21","date_gmt":"2025-10-24T12:35:21","guid":{"rendered":"https:\/\/mascoweb.com.ar\/tienda\/?post_type=product&#038;p=2954"},"modified":"2026-06-24T22:38:03","modified_gmt":"2026-06-25T01:38:03","slug":"combo-yenu-gatos-x-75-kg-bolson-piedras-sanitarias-x-25-kg","status":"publish","type":"product","link":"https:\/\/mascoweb.com.ar\/tienda\/producto\/combo-yenu-gatos-x-75-kg-bolson-piedras-sanitarias-x-25-kg\/","title":{"rendered":"Combo Yen\u00fa Gatos x 7,5 kg + Bols\u00f3n Piedras Sanitarias x 25 kg"},"content":{"rendered":"<p><strong>Yen\u00fa Gatos Adultos Alimento PREMIUM<\/strong><\/p>\n<p><strong>Salud del Sistema Digestivo:<\/strong>\u00a0Gracias a los<br \/>\ndiferentes tipos de fibras y carbohidratos<br \/>\nsolubles incorporados en la formulaci\u00f3n se<br \/>\nasegura un correcto funcionamiento del<br \/>\nsistema digestivo.<\/p>\n<p><strong>Reducci\u00f3n del Amon\u00edaco en las<br \/>\nDeyecciones:<\/strong>\u00a0Debido a compuestos<br \/>\nextra\u00eddos de plantas naturales se logra una<br \/>\nreducci\u00f3n de los aromas en las<br \/>\ndeposiciones las que presentan un score<br \/>\nadecuado para su f\u00e1cil eliminaci\u00f3n.<\/p>\n<p><strong>Dentici\u00f3n Reforzada:<\/strong>\u00a0El uso balanceado de<br \/>\nminerales favorece la salud bucal, ya que<br \/>\nbrinda una correcta proporci\u00f3n entre el<br \/>\ncalcio y el f\u00f3sforo, minerales importantes<br \/>\npara asegurar dientes sanos y fuertes.<\/p>\n<p><strong>33% de prote\u00ednas- Indicado para gatos adultos mayores de 12 meses &#8211; Contiene 7.5kg<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p><strong>Yen\u00fa Gatos Adultos Alimento PREMIUM<\/strong><\/p>\n<p><strong>Salud del Sistema Digestivo:<\/strong>\u00a0Gracias a los<br \/>\ndiferentes tipos de fibras y carbohidratos<br \/>\nsolubles incorporados en la formulaci\u00f3n se<br \/>\nasegura un correcto funcionamiento del<br \/>\nsistema digestivo.<\/p>\n","protected":false},"featured_media":2955,"template":"","meta":{"_gspb_post_css":"","_joinchat":[]},"product_brand":[70],"product_cat":[144,61,79],"product_tag":[32,64],"class_list":["post-2954","product","type-product","status-publish","has-post-thumbnail","product_brand-yenu","product_cat-gatosadultos","product_cat-promociones","product_cat-sanitariosehigiene","product_tag-adultos","product_tag-premium","first","instock","shipping-taxable","purchasable","product-type-simple"],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/mascoweb.com.ar\/tienda\/wp-json\/wp\/v2\/product\/2954","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mascoweb.com.ar\/tienda\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/mascoweb.com.ar\/tienda\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mascoweb.com.ar\/tienda\/wp-json\/wp\/v2\/media\/2955"}],"wp:attachment":[{"href":"https:\/\/mascoweb.com.ar\/tienda\/wp-json\/wp\/v2\/media?parent=2954"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/mascoweb.com.ar\/tienda\/wp-json\/wp\/v2\/product_brand?post=2954"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/mascoweb.com.ar\/tienda\/wp-json\/wp\/v2\/product_cat?post=2954"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/mascoweb.com.ar\/tienda\/wp-json\/wp\/v2\/product_tag?post=2954"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}